{"id":612,"date":"2024-03-05T17:55:52","date_gmt":"2024-03-05T17:55:52","guid":{"rendered":"https:\/\/anthemofgrace.com\/nick-%e0%a8%b9%e0%a8%be%e0%a8%b2-%e0%a8%ac%e0%a8%be%e0%a8%b0%e0%a9%87\/"},"modified":"2024-03-25T15:04:23","modified_gmt":"2024-03-25T15:04:23","slug":"nick-%e0%a8%b9%e0%a8%be%e0%a8%b2-%e0%a8%ac%e0%a8%be%e0%a8%b0%e0%a9%87","status":"publish","type":"page","link":"https:\/\/anthemofgrace.com\/es\/nick-%e0%a8%b9%e0%a8%be%e0%a8%b2-%e0%a8%ac%e0%a8%be%e0%a8%b0%e0%a9%87\/?lang=pa","title":{"rendered":"Sobre Nick Hall"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1709820772512\"><div class=\"wpb_column vc_column_container vc_col-sm-7\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h1 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl\"><span class=\"vcex-heading-inner wpex-inline-block\">Sobre Nick Hall<\/span><\/h1>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Nick Hall es el fundador y presidente de Pulse Evangelism, autor del libro Reset y una de las voces de evangelismo m\u00e1s destacadas de la actualidad para la pr\u00f3xima generaci\u00f3n. Ha compartido el evangelio con m\u00e1s de 330 millones de personas en todo el mundo y sabe que Dios a\u00fan no ha terminado.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div style=\"color:#ff8255;font-style:italic;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpb_content_element  vc_custom_1709744515558 intro-text\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u201cMi vida existe para poner a Jes\u00fas en el pulso de una generaci\u00f3n\u2018. - Nick Hall<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Lo que comenz\u00f3 en 2006 como un acto de fe para compartir la esperanza en Jes\u00fas en el campus de su universidad, ha crecido hasta convertirse en un movimiento mundial para alcanzar a los perdidos, formando a evangelistas comprometidos a transformar a su generaci\u00f3n con el Evangelio de todas las maneras necesarias.<\/p>\n<p>Nick tambi\u00e9n se desempe\u00f1a como presidente y director ejecutivo del Comit\u00e9 Ejecutivo de la Asociaci\u00f3n Nacional de Evang\u00e9licos y de The Table Coalition. Vive en Minneapolis, MN, con su esposa Tiffany y tres hijos.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-5\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-image.vcex_6a573fda31a15 .vcex-image-inner{max-width:325px;}.vcex-image.vcex_6a573fda31a15 .vcex-image-img{height:370px;}<\/style><figure class=\"vcex-image vcex-module textcenter nick-hall-image vcex_6a573fda31a15\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block vc_custom_1711114666517\"><img width=\"1400\" height=\"2142\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color.png\" class=\"vcex-image-img wpex-align-middle wpex-object-contain\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color.png 1400w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color-196x300.png 196w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color-669x1024.png 669w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color-768x1175.png 768w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color-1004x1536.png 1004w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/NickHall_Photo-Color-1339x2048.png 1339w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><\/div><\/figure><h1 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-text-center nick-hall-heading\"><span class=\"vcex-heading-inner wpex-inline-block\">Nick Hall<\/span><\/h1><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1709755882506 vc_row-o-content-middle vc_row-flex wpex-vc_row-has-fill wpex-vc-row-stretched\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1709744234856\"><div class=\"wpb_wrapper\">\n\t<div style=\"color:#ff8255;font-family:ZTBrosOskon90s;font-size:32px;font-weight:400;text-align:center;line-height:40px;width:90%;font-style:italic;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpex-max-w-100 wpex-mx-auto wpb_content_element  vc_custom_1709744365898 orange-border-text\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>\u201cLa gente necesita a Jes\u00fas, pero solo escuchar\u00e1 el evangelio si hay mensajeros confiables.\u201d \u2013 Nick Hall<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Nick Hall es el fundador y presidente de Nich Hall Plus Evangelism, autor del libro Reset, y una de las voces de evangelismo m\u00e1s importantes de la actualidad para la pr\u00f3xima generaci\u00f3n. Ha predicado el evangelio a m\u00e1s de 330 millones de personas en todo el mundo y sabe que Dios a\u00fan no ha terminado\u2026","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-612","page","type-page","status-publish","hentry","entry","no-media"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":0,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages\/612\/revisions"}],"wp:attachment":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/media?parent=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}