{"id":3793,"date":"2024-03-15T17:53:53","date_gmt":"2024-03-15T17:53:53","guid":{"rendered":"https:\/\/anthemofgrace.com\/ekstra\/"},"modified":"2024-04-03T19:45:17","modified_gmt":"2024-04-03T19:45:17","slug":"ekstra","status":"publish","type":"page","link":"https:\/\/anthemofgrace.com\/es\/ekstra\/?lang=jv","title":{"rendered":"Extra"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid wpb_animate_when_almost_visible wpb_fadeIn fadeIn vc_custom_1709820772512\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-heading.vcex_6a571ad461dbd{text-transform:uppercase;}<\/style><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-text-center wpex-italic vcex_6a571ad461dbd\"><span class=\"vcex-heading-inner wpex-inline-block\">Caracter\u00edsticas de Bonus: Profundizando en Grace<\/span><\/h2>\n\t<div style=\"font-size:22px;text-align:center;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Verifica este clip extra de la transmisi\u00f3n de Anthem of Grace<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1710526085969\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573574723\"><a href=\"https:\/\/youtu.be\/mVUYXYmPVBo\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-Anthem-of-Grace.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-Anthem-of-Grace.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-Anthem-of-Grace-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad46333e{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481405454 vcex_6a571ad46333e\"><span class=\"vcex-heading-inner wpex-inline-block\">Transmisi\u00f3n del Viernes Santo;<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Himno de Gracia<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573645349\"><a href=\"https:\/\/youtu.be\/094CLGcaP1A\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-amazing-grace.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-amazing-grace.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-amazing-grace-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad46450d{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1710527355797 vcex_6a571ad46450d\"><span class=\"vcex-heading-inner wpex-inline-block\">Sublime Gracia;<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Miel San Marcos<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573658007\"><a href=\"https:\/\/youtu.be\/wAh5I4rzCVM\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-Meil-San-Marcos.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-Meil-San-Marcos.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-Meil-San-Marcos-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad465f69{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481503462 vcex_6a571ad465f69\"><span class=\"vcex-heading-inner wpex-inline-block\">Entrevista a Nick Hall<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Miel San Marcos<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573667590\"><a href=\"https:\/\/youtu.be\/xGq_f7iodtc\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-NO-HAY-LUGAR-MAS-ALTO.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-NO-HAY-LUGAR-MAS-ALTO.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-NO-HAY-LUGAR-MAS-ALTO-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad467157{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481573214 vcex_6a571ad467157\"><span class=\"vcex-heading-inner wpex-inline-block\">No hay ning\u00fan lugar m\u00e1s alto<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Miel San Marcos <\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573635062\"><a href=\"https:\/\/youtu.be\/SMWLE-hyMFQ\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad468348{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481636290 vcex_6a571ad468348\"><span class=\"vcex-heading-inner wpex-inline-block\">Sublime Gracia;<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Steven Curtis Chapman<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573681474\"><a href=\"https:\/\/youtu.be\/yRU7qDySWWc\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-scc.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-scc.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-interview-scc-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad469697{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481503462 vcex_6a571ad469697\"><span class=\"vcex-heading-inner wpex-inline-block\">Entrevista a Nick Hall<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Steven Curtis Chapman<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module textcenter\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block overlay-parent overlay-parent-video-icon_2 wpex-overflow-hidden vc_custom_1711573625128\"><a href=\"https:\/\/youtu.be\/MWDzdfMIjrs\" class=\"wpex-lightbox\"><img width=\"500\" height=\"281\" src=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1.jpg 500w, https:\/\/anthemofgrace.com\/wp-content\/uploads\/2024\/03\/thumb-MORE-TO-THIS-LIFE-1-300x169.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\n<div class=\"overlay-video-icon_2 theme-overlay wpex-absolute wpex-inset-0 wpex-flex wpex-items-center wpex-justify-center\" aria-hidden=\"true\">\n    <span class=\"overlay-bg wpex-bg-black wpex-block wpex-absolute wpex-inset-0 wpex-opacity-20\"><\/span><svg class=\"overlay__video-svg wpex-transition-transform wpex-duration-300 wpex-max-w-20 wpex-relative\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" height=\"60px\" width=\"60px\" viewbox=\"0 0 24 24\" fill=\"#FFFFFF\"><path d=\"M8 6.82v10.36c0 .79.87 1.27 1.54.84l8.14-5.18c.62-.39.62-1.29 0-1.69L9.54 5.98C8.87 5.55 8 6.03 8 6.82z\"\/><\/svg>\n<\/div>\n<\/a><\/div><\/figure><style>.vcex-heading.vcex_6a571ad46a402{text-transform:uppercase;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-italic vc_custom_1711481752930 vcex_6a571ad46a402\"><span class=\"vcex-heading-inner wpex-inline-block\">M\u00e1s vida para esta vida<\/span><\/h3>\n\t<div style=\"font-size:22px;\" class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Steven Curtis Chapman<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Caracter\u00edsticas Adicionales: Sum\u00e9rgete en Grace Mira estos clips extra de la transmisi\u00f3n de Anthem of Grace \"Anthem of Grace Good Friday Broadcast\" \"Amazing Grace\" de Anthem of Grace Honey San Marcos Entrevista a Nick Hall Honey San Marcos No hay lugar m\u00e1s alto Honey San Marcos \"Amazing Grace\" Steven Curtis Chapman Entrevista a Nick Hall Steven Curtis Chapman M\u00e1s...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-3793","page","type-page","status-publish","hentry","entry","no-media"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages\/3793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/comments?post=3793"}],"version-history":[{"count":0,"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/pages\/3793\/revisions"}],"wp:attachment":[{"href":"https:\/\/anthemofgrace.com\/es\/wp-json\/wp\/v2\/media?parent=3793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}